{"id":343,"date":"2024-02-28T23:54:59","date_gmt":"2024-02-29T02:54:59","guid":{"rendered":"https:\/\/divulga.unila.edu.br\/gazeta\/?p=343"},"modified":"2024-02-28T23:55:01","modified_gmt":"2024-02-29T02:55:01","slug":"fortalecendo-a-comunidade-e-transformando-vidas","status":"publish","type":"post","link":"https:\/\/divulga.unila.edu.br\/gazeta\/2024\/02\/28\/fortalecendo-a-comunidade-e-transformando-vidas\/","title":{"rendered":"Fortalecendo a comunidade e transformando vidas"},"content":{"rendered":"\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong>Conhe\u00e7a um pouco do trabalho do Conselho Comunit\u00e1rio da Vila C<\/strong><\/p><\/blockquote><\/figure>\n\n\n\n<p>O Conselho Comunit\u00e1rio da Vila C (CCVC) surgiu em 2004, ap\u00f3s o fim da constru\u00e7\u00e3o da barragem de Itaipu, e est\u00e1 instalado no espa\u00e7o onde antes existia um mercado popular mantido pelo projeto Energia Solid\u00e1ria. O projeto foi entregue aos moradores, e foi nesse momento que o nome Conselho Comunit\u00e1rio foi adotado.&nbsp;<\/p>\n\n\n\n<p>Apesar de ter autonomia e de ser considerado uma associa\u00e7\u00e3o sem fins lucrativos, o Conselho tem a Itaipu como principal apoiadora at\u00e9 os dias de hoje.&nbsp;<\/p>\n\n\n\n<p>Jessica Driele Rossetti come\u00e7ou sua trajet\u00f3ria no Conselho trabalhando na secretaria e desde 2020 exerce as fun\u00e7\u00f5es de coordenadora. Ela conta que o objetivo do local \u00e9 a promo\u00e7\u00e3o de a\u00e7\u00f5es sociais que melhorem a qualidade de vida e tragam cultura, educa\u00e7\u00e3o e sa\u00fade aos moradores. \u201cApesar de ter Vila C no nome, hoje o projeto recebe pessoas de todo o distrito norte da cidade, e \u00e9 o \u00fanico que possui uma estrutura desse tipo na regi\u00e3o\u201d.<\/p>\n\n\n\n<p>A \u00e1rea de 2 mil metros quadrados \u00e9 muito bem utilizada pelo Conselho, que possui quadra de esportes, salas de m\u00fasica, salas de aula, dentre outros espa\u00e7os. Atualmente, cerca de 800 pessoas s\u00e3o atendidas pelas a\u00e7\u00f5es do CCVC, em 19 oficinas direcionadas para todas as idades. S\u00e3o ministradas aulas de xadrez, bal\u00e9, futsal, badminton, jud\u00f4, teatro, viol\u00e3o, teclado, piano, artesanato, entre outras. Para os adultos tamb\u00e9m s\u00e3o oferecidos cursos de inform\u00e1tica, corte e costura, cabeleireiro e manicure, al\u00e9m de outros cursos ministrados por entidades parceiras.&nbsp;<\/p>\n\n\n\n<p>J\u00e1 os idosos podem participar das atividades f\u00edsicas oferecidas nas manh\u00e3s de segunda e quarta-feira, e das atividades de educa\u00e7\u00e3o em sa\u00fade desenvolvidas em parceria com a Unidade B\u00e1sica de Sa\u00fade Cidade Nova, onde s\u00e3o realizadas palestras e rodas de conversa com nutricionistas, fisioterapeutas e psic\u00f3logos.<\/p>\n\n\n\n<p>Duas vezes por ano tamb\u00e9m s\u00e3o oferecidos cursos profissionalizantes de auxiliar administrativo, de onde saem formados 25 alunos a cada semestre. O curso \u00e9 oferecido em parceria com o SENAI, que cede os professores respons\u00e1veis pelas atividades.<\/p>\n\n\n\n<p>Atualmente, cerca de trinta colaboradores trabalham no CCVC, dentre eles funcion\u00e1rios efetivos do Conselho, professores cedidos pela Secretaria de Esportes do munic\u00edpio, e pela Funda\u00e7\u00e3o Cultural (do projeto Foz Fazendo Arte), um professor cedido pelo Conselho do Idoso, al\u00e9m de professores volunt\u00e1rios, que desenvolvem atividades de desenho e de Sipalki-Do, uma arte marcial oriental.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"668\" src=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-1024x668.png\" alt=\"\" class=\"wp-image-346\" srcset=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-1024x668.png 1024w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-300x196.png 300w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-768x501.png 768w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-1536x1002.png 1536w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-205x134.png 205w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-480x313.png 480w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28-816x533.png 816w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.28.png 1618w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center\"><strong>O espa\u00e7o do CCVC inclui um gin\u00e1sio com quadra poliesportiva<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pela comunidade e para a comunidade<\/strong><\/h2>\n\n\n\n<p>J\u00e9ssica Rossetti comenta que praticamente todos os colaboradores e professores s\u00e3o moradores da Vila C, o que ajuda a fortalecer o v\u00ednculo com a comunidade. Entre esses nomes est\u00e1 a professora de bal\u00e9 Anna Carolina Gomes, moradora da Vila C que come\u00e7ou a dan\u00e7ar bal\u00e9 com 4 anos no CCVC, at\u00e9 se formar bailarina, o que lhe rendeu bolsas de estudos em escolas. Anna retornou ao CCVC aos 15 anos, como estagi\u00e1ria da professora, at\u00e9 se tornar professora titular.&nbsp;<\/p>\n\n\n\n<p>Educadora f\u00edsica de forma\u00e7\u00e3o, Anna \u00e9 respons\u00e1vel por dar aulas e organizar os espet\u00e1culos de dan\u00e7a. Em 2022 conseguiu levar suas alunas para conhecer a Escola de Ballet Bolshoi, com sede na cidade de Joinville, em Santa Catarina.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"824\" height=\"1010\" src=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.42.png\" alt=\"\" class=\"wp-image-349\" srcset=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.42.png 824w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.42-245x300.png 245w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.42-768x941.png 768w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.42-205x251.png 205w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.42-480x588.png 480w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.42-816x1000.png 816w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Anna Carolina Gomes,\u00a0professora de bal\u00e9 do CCVC<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Outra atividade que se destaca \u00e9 o Badminton, esporte do professor Adriano Fiori. O esporte, que cada vez conquista mais praticantes entre crian\u00e7as e adolescentes, demanda a compra de equipamentos caros, e \u00e9 oferecido gratuitamente. Sem esse incentivo,\u00a0 os jovens praticantes provavelmente nunca teriam iniciado a pr\u00e1tica. Em 2022 a equipe do CCVC participou do Campeonato Paranaense de Badminton, conquistando 17 medalhas, um resultado in\u00e9dito para a cidade.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Estreitando la\u00e7os com a Universidade<\/strong><\/h2>\n\n\n\n<p>O Conselho est\u00e1 organizando uma parceria com a Unila e com a Unioeste. O plano \u00e9 receber professores e acad\u00eamicos para realizar atividades com as crian\u00e7as e adolescentes, al\u00e9m de ampliar as a\u00e7\u00f5es para as escolas do bairro. Inicialmente ser\u00e3o aulas de matem\u00e1tica e portugu\u00eas. Tamb\u00e9m est\u00e1 em curso para 2024 a realiza\u00e7\u00e3o de oficinas na \u00e1rea de rob\u00f3tica em parceria com o Parque Tecnol\u00f3gico de Itaipu.<\/p>\n\n\n\n<p>A professora Mariana Cortez, do curso de Letras da Universidade Federal da Integra\u00e7\u00e3o Latino-americana (Unila), explica que ampliar as a\u00e7\u00f5es da Unila para a comunidade de toda a cidade de Foz do Igua\u00e7u \u00e9 um compromisso estabelecido pelo Plano de Desenvolvimento Institucional (PDI) da institui\u00e7\u00e3o. Ela ainda refor\u00e7a que a Unila possui um compromisso com o desenvolvimento social e cultural do munic\u00edpio.<\/p>\n\n\n\n<p>Entre uma das atividades planejadas para o pr\u00f3ximo ano entre a Unila e o CCVC est\u00e1 o projeto Vivendo Livros, que busca estabelecer uma biblioteca comunit\u00e1ria no espa\u00e7o onde atualmente est\u00e1 o Conselho.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"804\" height=\"544\" src=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.50.png\" alt=\"\" class=\"wp-image-351\" srcset=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.50.png 804w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.50-300x203.png 300w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.50-768x520.png 768w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.50-205x139.png 205w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.50-480x325.png 480w\" sizes=\"(max-width: 804px) 100vw, 804px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>Entre conquistas e\u00a0desafios<\/strong><\/h2>\n\n\n\n<p>Mesmo com todo suporte recebido, o CCVC vive uma luta di\u00e1ria para continuar aberto, pois possui muitos gastos para manter a estrutura e o espa\u00e7o f\u00edsico funcionais e bem preservados. A coordenadora do Conselho, J\u00e9ssica Rossetti, conta que precisa abrir m\u00e3o de projetos que gostariam de executar por falta de recursos. \u201cHoje n\u00f3s temos uma cozinha industrial praticamente montada, e a ideia era no futuro oferecer um curso de gastronomia para a comunidade, mas calculamos que gastar\u00edamos em m\u00e9dia quatro mil reais por m\u00eas com insumos e n\u00e3o temos esse dinheiro\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"542\" src=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.58-1.png\" alt=\"\" class=\"wp-image-353\" srcset=\"https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.58-1.png 810w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.58-1-300x201.png 300w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.58-1-768x514.png 768w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.58-1-205x137.png 205w, https:\/\/divulga.unila.edu.br\/gazeta\/wp-content\/uploads\/sites\/36\/2024\/02\/Captura-de-Tela-2024-02-28-as-22.33.58-1-480x321.png 480w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n<\/div>\n\n\n<p>Apesar de todas as dificuldades, a Coordenadora se mostra otimista com o trabalho realizado e celebra alguns dos feitos conseguidos pela atual gest\u00e3o. \u201dQuando come\u00e7amos o trabalho, a CCVC estava com quase meio milh\u00e3o em d\u00edvidas deixadas por gest\u00f5es passadas, entre empr\u00e9stimos e processos trabalhistas. Conseguimos correr atr\u00e1s e pagar quase tudo. Hoje resta apenas oitenta mil reais para pagar e estamos confiantes que logo conseguiremos\u201d.\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Reportagem: Ozires Kelvin G. Vieira<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a um pouco do trabalho do Conselho Comunit\u00e1rio da Vila C O Conselho Comunit\u00e1rio da Vila C (CCVC) surgiu em 2004, ap\u00f3s o fim da constru\u00e7\u00e3o da barragem de Itaipu, e est\u00e1 instalado no espa\u00e7o onde antes existia um mercado popular mantido pelo projeto Energia Solid\u00e1ria. O projeto foi entregue aos moradores, e foi nesse momento que o nome Conselho Comunit\u00e1rio foi adotado.&nbsp; Apesar de ter autonomia e de ser considerado uma associa\u00e7\u00e3o sem fins lucrativos, o Conselho tem a Itaipu como principal apoiadora at\u00e9 os dias de hoje.&nbsp; Jessica Driele Rossetti come\u00e7ou sua trajet\u00f3ria no Conselho trabalhando na secretaria e desde 2020 exerce as fun\u00e7\u00f5es de coordenadora. Ela conta que o objetivo do local \u00e9 a promo\u00e7\u00e3o de a\u00e7\u00f5es sociais que melhorem a qualidade de vida e tragam cultura, educa\u00e7\u00e3o e sa\u00fade aos moradores. \u201cApesar de ter Vila C no nome, hoje o projeto recebe pessoas de todo o distrito norte da cidade, e \u00e9 o \u00fanico que possui uma estrutura desse tipo na regi\u00e3o\u201d. A \u00e1rea de 2 mil metros quadrados \u00e9 muito bem utilizada pelo Conselho, que possui quadra de esportes, salas de m\u00fasica, salas de aula, dentre outros espa\u00e7os. Atualmente, cerca de 800 pessoas s\u00e3o atendidas pelas a\u00e7\u00f5es do CCVC, em 19 oficinas direcionadas para todas as idades. S\u00e3o ministradas aulas de xadrez, bal\u00e9, futsal, badminton, jud\u00f4, teatro, viol\u00e3o, teclado, piano, artesanato, entre outras. Para os adultos tamb\u00e9m s\u00e3o oferecidos cursos de inform\u00e1tica, corte e costura, cabeleireiro e manicure, al\u00e9m de outros cursos ministrados por entidades parceiras.&nbsp; J\u00e1 os idosos podem participar das atividades f\u00edsicas oferecidas nas manh\u00e3s de segunda e quarta-feira, e das atividades de educa\u00e7\u00e3o em sa\u00fade desenvolvidas em parceria com a Unidade B\u00e1sica de Sa\u00fade Cidade Nova, onde s\u00e3o realizadas palestras e rodas de conversa com nutricionistas, fisioterapeutas e psic\u00f3logos. Duas vezes por ano tamb\u00e9m s\u00e3o oferecidos cursos profissionalizantes de auxiliar administrativo, de onde saem formados 25 alunos a cada semestre. O curso \u00e9 oferecido em parceria com o SENAI, que cede os professores respons\u00e1veis pelas atividades. Atualmente, cerca de trinta colaboradores trabalham no CCVC, dentre eles funcion\u00e1rios efetivos do Conselho, professores cedidos pela Secretaria de Esportes do munic\u00edpio, e pela Funda\u00e7\u00e3o Cultural (do projeto Foz Fazendo Arte), um professor cedido pelo Conselho do Idoso, al\u00e9m de professores volunt\u00e1rios, que desenvolvem atividades de desenho e de Sipalki-Do, uma arte marcial oriental. O espa\u00e7o do CCVC inclui um gin\u00e1sio com quadra poliesportiva Pela comunidade e para a comunidade J\u00e9ssica Rossetti comenta que praticamente todos os colaboradores e professores s\u00e3o moradores da Vila C, o que ajuda a fortalecer o v\u00ednculo com a comunidade. Entre esses nomes est\u00e1 a professora de bal\u00e9 Anna Carolina Gomes, moradora da Vila C que come\u00e7ou a dan\u00e7ar bal\u00e9 com 4 anos no CCVC, at\u00e9 se formar bailarina, o que lhe rendeu bolsas de estudos em escolas. Anna retornou ao CCVC aos 15 anos, como estagi\u00e1ria da professora, at\u00e9 se tornar professora titular.&nbsp; Educadora f\u00edsica de forma\u00e7\u00e3o, Anna \u00e9 respons\u00e1vel por dar aulas e organizar os espet\u00e1culos de dan\u00e7a. Em 2022 conseguiu levar suas alunas para conhecer a Escola de Ballet Bolshoi, com sede na cidade de Joinville, em Santa Catarina.&nbsp; Anna Carolina Gomes,\u00a0professora de bal\u00e9 do CCVC Outra atividade que se destaca \u00e9 o Badminton, esporte do professor Adriano Fiori. O esporte, que cada vez conquista mais praticantes entre crian\u00e7as e adolescentes, demanda a compra de equipamentos caros, e \u00e9 oferecido gratuitamente. Sem esse incentivo,\u00a0 os jovens praticantes provavelmente nunca teriam iniciado a pr\u00e1tica. Em 2022 a equipe do CCVC participou do Campeonato Paranaense de Badminton, conquistando 17 medalhas, um resultado in\u00e9dito para a cidade.\u00a0 Estreitando la\u00e7os com a Universidade O Conselho est\u00e1 organizando uma parceria com a Unila e com a Unioeste. O plano \u00e9 receber professores e acad\u00eamicos para realizar atividades com as crian\u00e7as e adolescentes, al\u00e9m de ampliar as a\u00e7\u00f5es para as escolas do bairro. Inicialmente ser\u00e3o aulas de matem\u00e1tica e portugu\u00eas. Tamb\u00e9m est\u00e1 em curso para 2024 a realiza\u00e7\u00e3o de oficinas na \u00e1rea de rob\u00f3tica em parceria com o Parque Tecnol\u00f3gico de Itaipu. A professora Mariana Cortez, do curso de Letras da Universidade Federal da Integra\u00e7\u00e3o Latino-americana (Unila), explica que ampliar as a\u00e7\u00f5es da Unila para a comunidade de toda a cidade de Foz do Igua\u00e7u \u00e9 um compromisso estabelecido pelo Plano de Desenvolvimento Institucional (PDI) da institui\u00e7\u00e3o. Ela ainda refor\u00e7a que a Unila possui um compromisso com o desenvolvimento social e cultural do munic\u00edpio. Entre uma das atividades planejadas para o pr\u00f3ximo ano entre a Unila e o CCVC est\u00e1 o projeto Vivendo Livros, que busca estabelecer uma biblioteca comunit\u00e1ria no espa\u00e7o onde atualmente est\u00e1 o Conselho.&nbsp; Entre conquistas e\u00a0desafios Mesmo com todo suporte recebido, o CCVC vive uma luta di\u00e1ria para continuar aberto, pois possui muitos gastos para manter a estrutura e o espa\u00e7o f\u00edsico funcionais e bem preservados. A coordenadora do Conselho, J\u00e9ssica Rossetti, conta que precisa abrir m\u00e3o de projetos que gostariam de executar por falta de recursos. \u201cHoje n\u00f3s temos uma cozinha industrial praticamente montada, e a ideia era no futuro oferecer um curso de gastronomia para a comunidade, mas calculamos que gastar\u00edamos em m\u00e9dia quatro mil reais por m\u00eas com insumos e n\u00e3o temos esse dinheiro\u201d. Apesar de todas as dificuldades, a Coordenadora se mostra otimista com o trabalho realizado e celebra alguns dos feitos conseguidos pela atual gest\u00e3o. \u201dQuando come\u00e7amos o trabalho, a CCVC estava com quase meio milh\u00e3o em d\u00edvidas deixadas por gest\u00f5es passadas, entre empr\u00e9stimos e processos trabalhistas. Conseguimos correr atr\u00e1s e pagar quase tudo. Hoje resta apenas oitenta mil reais para pagar e estamos confiantes que logo conseguiremos\u201d.\u00a0 Reportagem: Ozires Kelvin G. Vieira<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-343","post","type-post","status-publish","format-standard","hentry","category-4a-edicao"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"htmega_size_585x295":false,"htmega_size_1170x536":false,"htmega_size_396x360":false,"tainacan-small":false,"tainacan-medium":false,"tainacan-medium-full":false,"tainacan-large-full":false,"post-thumbnail":false,"post-image":false,"post-image-thumb":false},"uagb_author_info":{"display_name":"okg.vieira.2021","author_link":"https:\/\/divulga.unila.edu.br\/gazeta\/author\/okgvieira2021\/"},"uagb_comment_info":1,"uagb_excerpt":"Conhe\u00e7a um pouco do trabalho do Conselho Comunit\u00e1rio da Vila C O Conselho Comunit\u00e1rio da Vila C (CCVC) surgiu em 2004, ap\u00f3s o fim da constru\u00e7\u00e3o da barragem de Itaipu, e est\u00e1 instalado no espa\u00e7o onde antes existia um mercado popular mantido pelo projeto Energia Solid\u00e1ria. O projeto foi entregue aos moradores, e foi nesse&hellip;","_links":{"self":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts\/343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/comments?post=343"}],"version-history":[{"count":1,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts\/343\/revisions"}],"predecessor-version":[{"id":355,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts\/343\/revisions\/355"}],"wp:attachment":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/media?parent=343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/categories?post=343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/tags?post=343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}