{"id":175,"date":"2023-11-03T17:32:01","date_gmt":"2023-11-03T20:32:01","guid":{"rendered":"https:\/\/divulga.unila.edu.br\/gazeta\/?p=175"},"modified":"2023-11-03T17:32:03","modified_gmt":"2023-11-03T20:32:03","slug":"unila-na-vila-paula-andrea-bolanos","status":"publish","type":"post","link":"https:\/\/divulga.unila.edu.br\/gazeta\/2023\/11\/03\/unila-na-vila-paula-andrea-bolanos\/","title":{"rendered":"Unila na Vila &#8211; Paula Andrea Bola\u00f1os"},"content":{"rendered":"\n<p><strong>Novos rostos e novas cores chegam a cada ano de todos os cantos da Am\u00e9rica- Latina.\u00a0<\/strong><\/p>\n\n\n\n<p>A Universidade Federal da Integra\u00e7\u00e3o Latino-Americana (UNILA) surgiu com o prop\u00f3sito de integrar o povo latino-americano e promover um interc\u00e2mbio cultural, cient\u00edfico e educacional entre seus povos. A universidade recebe anualmente muitos estudantes estrangeiros, que acabam encontrando resid\u00eancia na Vila C. Hoje vamos apresentar uma entre as mais diversas hist\u00f3rias de estudantes que vivem no bairro, a hist\u00f3ria da Paula Andrea Bola\u00f1os Valencia, que veio de Bogot\u00e1, capital da Col\u00f4mbia.&nbsp;<\/p>\n\n\n\n<p>A estudante se mudou para o Brasil em 2020, mas com a pandemia de covid-19 retornou para o seu pa\u00eds de origem. S\u00f3 em 2022 voltou para Foz do Igua\u00e7u para encontrar a irm\u00e3, que ficou morando por aqui. Moradora da Vila C h\u00e1 um ano e cinco meses, ela conta que tamb\u00e9m divide a kitnet com o seu bichinho de estima\u00e7\u00e3o \u201cPancho\u201d.&nbsp;<\/p>\n\n\n\n<p>Ela conta que o bairro \u00e9 um lugar tranquilo e familiar, onde as crian\u00e7as podem brincar nas ruas (raridade nos dias de hoje). Entre as mem\u00f3rias afetivas da estudante com a Vila C, est\u00e1 a sua rela\u00e7\u00e3o com a comida. Uma delas \u00e9 da feira gastron\u00f4mica cultural, onde ela vendia arepas e empanadas com a irm\u00e3 e a m\u00e3e, quando vinha visitar as filhas. A comida colombiana nem sempre era conhecida pela vizinhan\u00e7a, a exemplo de um dia em que um homem pediu uma empanada. \u201cQuando fui entregar a empanada para ele, ele disse que n\u00e3o era aquilo que tinha pedido. Eu tive que explicar para ele que aquilo era sim uma empanada, e ele poderia aprender algo novo. Eles foram muito am\u00e1veis na hora de comprar\u201d. A outra mem\u00f3ria que conta com saudades \u00e9 do Shawarma que vendiam a 5 reais no bairro. \u201cN\u00e3o eram t\u00e3o grandes assim, mas com dois desses e um suco dava para encher o dia inteiro\u201d.<\/p>\n\n\n\n<p>Paula refor\u00e7a que gosta muito de morar na Vila C. Mesmo precisando mudar de casa, sempre escolheu morar no bairro, e n\u00e3o quer ir embora. A estudante tamb\u00e9m aproveita a beleza do bairro para tirar fotos do p\u00f4r-do-sol, sempre bonitos em Foz do Igua\u00e7u.<\/p>\n\n\n\n<p>No bairro ela se sente segura, e conta achando engra\u00e7ado o fato de que quando sai de madrugada, mesmo os b\u00eabados s\u00e3o simp\u00e1ticos. \u201cA pessoa me cumprimenta, e eu cumprimento tamb\u00e9m\u201d. O que poderia melhorar, no entanto, seria a instala\u00e7\u00e3o de um ponto de \u00f4nibus inteligente, como os que existem na Vila A, pois nunca se sabe quando vai ficar sem internet e n\u00e3o conseguir consultar a que horas o \u00f4nibus passa.<\/p>\n\n\n\n<p>Para al\u00e9m de suas impress\u00f5es pessoais do bairro, Paula conta que muitos estudantes buscam morar na Vila C. \u201cConhe\u00e7o muitos unileiros (termo usado para se referir aos alunos que estudam na Unila) no bairro, \u00e9 at\u00e9 dif\u00edcil contar. Quando algu\u00e9m est\u00e1 aguardando no ponto de \u00f4nibus perto do Jardim Universit\u00e1rio de tarde, acaba procurando quem mora na Vila C, ent\u00e3o todo mundo pode ir junto para casa e ter mais seguran\u00e7a no trajeto\u201d.<\/p>\n\n\n\n<p>Ela conta tamb\u00e9m sobre uma piada feita entre o grupo de unileiros que moram no bairro.&nbsp; \u201cSe encher a represa, vamos nos inundar todos juntos\u201d. Ali\u00e1s, Paula menciona que costumam ouvir um barulhinho todos os dias, \u00e0s 20h da noite. Acreditam que o zumbido seja da represa, pois todos podem ouvi-lo.<\/p>\n\n\n\n<p><em>Reportagem:&nbsp;<\/em><\/p>\n\n\n\n<p><em>Luis Ignacio Mart\u00ednez Segura\u00a0e Jos\u00e9 Chucuya<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novos rostos e novas cores chegam a cada ano de todos os cantos da Am\u00e9rica- Latina.\u00a0 A Universidade Federal da Integra\u00e7\u00e3o Latino-Americana (UNILA) surgiu com o prop\u00f3sito de integrar o povo latino-americano e promover um interc\u00e2mbio cultural, cient\u00edfico e educacional entre seus povos. A universidade recebe anualmente muitos estudantes estrangeiros, que acabam encontrando resid\u00eancia na Vila C. Hoje vamos apresentar uma entre as mais diversas hist\u00f3rias de estudantes que vivem no bairro, a hist\u00f3ria da Paula Andrea Bola\u00f1os Valencia, que veio de Bogot\u00e1, capital da Col\u00f4mbia.&nbsp; A estudante se mudou para o Brasil em 2020, mas com a pandemia de covid-19 retornou para o seu pa\u00eds de origem. S\u00f3 em 2022 voltou para Foz do Igua\u00e7u para encontrar a irm\u00e3, que ficou morando por aqui. Moradora da Vila C h\u00e1 um ano e cinco meses, ela conta que tamb\u00e9m divide a kitnet com o seu bichinho de estima\u00e7\u00e3o \u201cPancho\u201d.&nbsp; Ela conta que o bairro \u00e9 um lugar tranquilo e familiar, onde as crian\u00e7as podem brincar nas ruas (raridade nos dias de hoje). Entre as mem\u00f3rias afetivas da estudante com a Vila C, est\u00e1 a sua rela\u00e7\u00e3o com a comida. Uma delas \u00e9 da feira gastron\u00f4mica cultural, onde ela vendia arepas e empanadas com a irm\u00e3 e a m\u00e3e, quando vinha visitar as filhas. A comida colombiana nem sempre era conhecida pela vizinhan\u00e7a, a exemplo de um dia em que um homem pediu uma empanada. \u201cQuando fui entregar a empanada para ele, ele disse que n\u00e3o era aquilo que tinha pedido. Eu tive que explicar para ele que aquilo era sim uma empanada, e ele poderia aprender algo novo. Eles foram muito am\u00e1veis na hora de comprar\u201d. A outra mem\u00f3ria que conta com saudades \u00e9 do Shawarma que vendiam a 5 reais no bairro. \u201cN\u00e3o eram t\u00e3o grandes assim, mas com dois desses e um suco dava para encher o dia inteiro\u201d. Paula refor\u00e7a que gosta muito de morar na Vila C. Mesmo precisando mudar de casa, sempre escolheu morar no bairro, e n\u00e3o quer ir embora. A estudante tamb\u00e9m aproveita a beleza do bairro para tirar fotos do p\u00f4r-do-sol, sempre bonitos em Foz do Igua\u00e7u. No bairro ela se sente segura, e conta achando engra\u00e7ado o fato de que quando sai de madrugada, mesmo os b\u00eabados s\u00e3o simp\u00e1ticos. \u201cA pessoa me cumprimenta, e eu cumprimento tamb\u00e9m\u201d. O que poderia melhorar, no entanto, seria a instala\u00e7\u00e3o de um ponto de \u00f4nibus inteligente, como os que existem na Vila A, pois nunca se sabe quando vai ficar sem internet e n\u00e3o conseguir consultar a que horas o \u00f4nibus passa. Para al\u00e9m de suas impress\u00f5es pessoais do bairro, Paula conta que muitos estudantes buscam morar na Vila C. \u201cConhe\u00e7o muitos unileiros (termo usado para se referir aos alunos que estudam na Unila) no bairro, \u00e9 at\u00e9 dif\u00edcil contar. Quando algu\u00e9m est\u00e1 aguardando no ponto de \u00f4nibus perto do Jardim Universit\u00e1rio de tarde, acaba procurando quem mora na Vila C, ent\u00e3o todo mundo pode ir junto para casa e ter mais seguran\u00e7a no trajeto\u201d. Ela conta tamb\u00e9m sobre uma piada feita entre o grupo de unileiros que moram no bairro.&nbsp; \u201cSe encher a represa, vamos nos inundar todos juntos\u201d. Ali\u00e1s, Paula menciona que costumam ouvir um barulhinho todos os dias, \u00e0s 20h da noite. Acreditam que o zumbido seja da represa, pois todos podem ouvi-lo. Reportagem:&nbsp; Luis Ignacio Mart\u00ednez Segura\u00a0e Jos\u00e9 Chucuya<\/p>\n","protected":false},"author":87,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-175","post","type-post","status-publish","format-standard","hentry","category-2edicao"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"htmega_size_585x295":false,"htmega_size_1170x536":false,"htmega_size_396x360":false,"tainacan-small":false,"tainacan-medium":false,"tainacan-medium-full":false,"tainacan-large-full":false,"post-thumbnail":false,"post-image":false,"post-image-thumb":false},"uagb_author_info":{"display_name":"okg.vieira.2021","author_link":"https:\/\/divulga.unila.edu.br\/gazeta\/author\/okgvieira2021\/"},"uagb_comment_info":0,"uagb_excerpt":"Novos rostos e novas cores chegam a cada ano de todos os cantos da Am\u00e9rica- Latina.\u00a0 A Universidade Federal da Integra\u00e7\u00e3o Latino-Americana (UNILA) surgiu com o prop\u00f3sito de integrar o povo latino-americano e promover um interc\u00e2mbio cultural, cient\u00edfico e educacional entre seus povos. A universidade recebe anualmente muitos estudantes estrangeiros, que acabam encontrando resid\u00eancia na&hellip;","_links":{"self":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/comments?post=175"}],"version-history":[{"count":1,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts\/175\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/posts\/175\/revisions\/178"}],"wp:attachment":[{"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/media?parent=175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/categories?post=175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/divulga.unila.edu.br\/gazeta\/wp-json\/wp\/v2\/tags?post=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}